{"id":75430,"date":"2026-07-15T15:56:43","date_gmt":"2026-07-15T12:56:43","guid":{"rendered":"https:\/\/biljardi.fi\/?post_type=product&#038;p=75430"},"modified":"2026-07-15T16:17:03","modified_gmt":"2026-07-15T13:17:03","slug":"bulls-grip-wax","status":"publish","type":"product","link":"https:\/\/biljardi.fi\/en\/product\/bulls-grip-wax\/","title":{"rendered":"Bull&#8217;s Grip Wax"},"content":{"rendered":"<p>Bull&#8217;s Grip Wax<\/p>\n<p>A wax for your fingers that improves grip.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bull&#8217;s Grip Wax A wax for your fingers that improves grip.<\/p>\n","protected":false},"featured_media":75432,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[2241],"product_cat":[2047],"product_tag":[],"giftcard-category":[],"class_list":["post-75430","product","type-product","status-publish","has-post-thumbnail","product_brand-bulls","product_cat-accessories","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"exclude_global_add_ons":[],"addons":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bull&#039;s Grip Wax - Suomen Biljardimyynti Oy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/biljardi.fi\/en\/product\/bulls-grip-wax\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bull&#039;s Grip Wax - Suomen Biljardimyynti Oy\" \/>\n<meta property=\"og:description\" content=\"Bull&#8217;s Grip Wax A wax for your fingers that improves grip.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/biljardi.fi\/en\/product\/bulls-grip-wax\/\" \/>\n<meta property=\"og:site_name\" content=\"Suomen Biljardimyynti Oy\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T13:17:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/biljardi.fi\/wp-content\/uploads\/2026\/07\/bull-s-finger-grip-wax.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"626\" \/>\n\t<meta property=\"og:image:height\" content=\"467\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/biljardi.fi\\\/en\\\/product\\\/bulls-grip-wax\\\/\",\"url\":\"https:\\\/\\\/biljardi.fi\\\/en\\\/product\\\/bulls-grip-wax\\\/\",\"name\":\"Bull's Grip Wax - Suomen Biljardimyynti Oy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/biljardi.fi\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/biljardi.fi\\\/en\\\/product\\\/bulls-grip-wax\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/biljardi.fi\\\/en\\\/product\\\/bulls-grip-wax\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/biljardi.fi\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/bull-s-finger-grip-wax.jpg\",\"datePublished\":\"2026-07-15T12:56:43+00:00\",\"dateModified\":\"2026-07-15T13:17:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/biljardi.fi\\\/en\\\/product\\\/bulls-grip-wax\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/biljardi.fi\\\/en\\\/product\\\/bulls-grip-wax\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/biljardi.fi\\\/en\\\/product\\\/bulls-grip-wax\\\/#primaryimage\",\"url\":\"https:\\\/\\\/biljardi.fi\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/bull-s-finger-grip-wax.jpg\",\"contentUrl\":\"https:\\\/\\\/biljardi.fi\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/bull-s-finger-grip-wax.jpg\",\"width\":626,\"height\":467},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/biljardi.fi\\\/en\\\/product\\\/bulls-grip-wax\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Etusivu\",\"item\":\"https:\\\/\\\/biljardi.fi\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/biljardi.fi\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bull&#8217;s Grip Wax\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/biljardi.fi\\\/#website\",\"url\":\"https:\\\/\\\/biljardi.fi\\\/\",\"name\":\"Suomen Biljardimyynti Oy\",\"description\":\"Biljardip\u00f6yd\u00e4t, Biljardi, Darts, Ilmakiekko, P\u00f6yt\u00e4jalkapallo\",\"publisher\":{\"@id\":\"https:\\\/\\\/biljardi.fi\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/biljardi.fi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/biljardi.fi\\\/#organization\",\"name\":\"Suomen Biljardimyynti Oy\",\"url\":\"https:\\\/\\\/biljardi.fi\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/biljardi.fi\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/biljardi.fi\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/logo_uus-1.png\",\"contentUrl\":\"https:\\\/\\\/biljardi.fi\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/logo_uus-1.png\",\"width\":360,\"height\":94,\"caption\":\"Suomen Biljardimyynti Oy\"},\"image\":{\"@id\":\"https:\\\/\\\/biljardi.fi\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bull's Grip Wax - Suomen Biljardimyynti Oy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/biljardi.fi\/en\/product\/bulls-grip-wax\/","og_locale":"en_US","og_type":"article","og_title":"Bull's Grip Wax - Suomen Biljardimyynti Oy","og_description":"Bull&#8217;s Grip Wax A wax for your fingers that improves grip.","og_url":"https:\/\/biljardi.fi\/en\/product\/bulls-grip-wax\/","og_site_name":"Suomen Biljardimyynti Oy","article_modified_time":"2026-07-15T13:17:03+00:00","og_image":[{"width":626,"height":467,"url":"https:\/\/biljardi.fi\/wp-content\/uploads\/2026\/07\/bull-s-finger-grip-wax.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/biljardi.fi\/en\/product\/bulls-grip-wax\/","url":"https:\/\/biljardi.fi\/en\/product\/bulls-grip-wax\/","name":"Bull's Grip Wax - Suomen Biljardimyynti Oy","isPartOf":{"@id":"https:\/\/biljardi.fi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/biljardi.fi\/en\/product\/bulls-grip-wax\/#primaryimage"},"image":{"@id":"https:\/\/biljardi.fi\/en\/product\/bulls-grip-wax\/#primaryimage"},"thumbnailUrl":"https:\/\/biljardi.fi\/wp-content\/uploads\/2026\/07\/bull-s-finger-grip-wax.jpg","datePublished":"2026-07-15T12:56:43+00:00","dateModified":"2026-07-15T13:17:03+00:00","breadcrumb":{"@id":"https:\/\/biljardi.fi\/en\/product\/bulls-grip-wax\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/biljardi.fi\/en\/product\/bulls-grip-wax\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/biljardi.fi\/en\/product\/bulls-grip-wax\/#primaryimage","url":"https:\/\/biljardi.fi\/wp-content\/uploads\/2026\/07\/bull-s-finger-grip-wax.jpg","contentUrl":"https:\/\/biljardi.fi\/wp-content\/uploads\/2026\/07\/bull-s-finger-grip-wax.jpg","width":626,"height":467},{"@type":"BreadcrumbList","@id":"https:\/\/biljardi.fi\/en\/product\/bulls-grip-wax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Etusivu","item":"https:\/\/biljardi.fi\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/biljardi.fi\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Bull&#8217;s Grip Wax"}]},{"@type":"WebSite","@id":"https:\/\/biljardi.fi\/#website","url":"https:\/\/biljardi.fi\/","name":"Suomen Biljardimyynti Oy","description":"Biljardip\u00f6yd\u00e4t, Biljardi, Darts, Ilmakiekko, P\u00f6yt\u00e4jalkapallo","publisher":{"@id":"https:\/\/biljardi.fi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/biljardi.fi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/biljardi.fi\/#organization","name":"Suomen Biljardimyynti Oy","url":"https:\/\/biljardi.fi\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/biljardi.fi\/#\/schema\/logo\/image\/","url":"https:\/\/biljardi.fi\/wp-content\/uploads\/2025\/10\/logo_uus-1.png","contentUrl":"https:\/\/biljardi.fi\/wp-content\/uploads\/2025\/10\/logo_uus-1.png","width":360,"height":94,"caption":"Suomen Biljardimyynti Oy"},"image":{"@id":"https:\/\/biljardi.fi\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/biljardi.fi\/en\/wp-json\/wp\/v2\/product\/75430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/biljardi.fi\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/biljardi.fi\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/biljardi.fi\/en\/wp-json\/wp\/v2\/comments?post=75430"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/biljardi.fi\/en\/wp-json\/wp\/v2\/media\/75432"}],"wp:attachment":[{"href":"https:\/\/biljardi.fi\/en\/wp-json\/wp\/v2\/media?parent=75430"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/biljardi.fi\/en\/wp-json\/wp\/v2\/product_brand?post=75430"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/biljardi.fi\/en\/wp-json\/wp\/v2\/product_cat?post=75430"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/biljardi.fi\/en\/wp-json\/wp\/v2\/product_tag?post=75430"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/biljardi.fi\/en\/wp-json\/wp\/v2\/giftcard-category?post=75430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}